{"id":76,"date":"2026-01-02T19:23:35","date_gmt":"2026-01-02T18:23:35","guid":{"rendered":"https:\/\/stefan.boeck.name\/de\/?p=76"},"modified":"2026-01-02T19:23:35","modified_gmt":"2026-01-02T18:23:35","slug":"perfmatters-von-der-idee-zum-launch","status":"publish","type":"post","link":"https:\/\/stefan.boeck.name\/de\/2026\/01\/02\/perfmatters-von-der-idee-zum-launch\/","title":{"rendered":"PerfMatters: Von der Idee zum Launch"},"content":{"rendered":"<p><em>\ud83c\uddec\ud83c\udde7 <a href=\"\/en\/perfmatters-from-idea-to-launch\/\">Read in English<\/a><\/em><\/p>\n<p>Der Ausl\u00f6ser war ein Blogpost von Stoyan Stefanov: <a href=\"https:\/\/calendar.perfplanet.com\/2025\/aislow\/\">AISlow<\/a>. Seine Idee: Lighthouse-Daten durch ein ML-Modell jagen und mit GPT verst\u00e4ndlich erkl\u00e4ren lassen.<\/p>\n<p>Das wollte ich ausprobieren.<\/p>\n<p>Das Ergebnis ist <strong>PerfMatters<\/strong> \u2013 ein Tool, das Web-Performance analysiert, den SpeedIndex vorhersagt und in verst\u00e4ndlicher Sprache erkl\u00e4rt, was eine Seite langsam macht.<\/p>\n<p>Der Stack:<\/p>\n<ul>\n<li>LightGBM f\u00fcr die Vorhersage (R\u00b2 = 0.90)<\/li>\n<li>SHAP f\u00fcr Feature-Importance<\/li>\n<li>GPT-4o-mini f\u00fcr die Zusammenfassung<\/li>\n<li>Laravel + FastAPI<\/li>\n<\/ul>\n<p>Stoyan hat es direkt getestet und ein paar Edge Cases gefunden \u2013 inzwischen gefixt. Danke daf\u00fcr!<\/p>\n<p>\u2192 <a href=\"https:\/\/perfmatters.org\">perfmatters.org<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83c\uddec\ud83c\udde7 Read in English Der Ausl\u00f6ser war ein Blogpost von Stoyan Stefanov: AISlow. Seine Idee: Lighthouse-Daten durch ein ML-Modell jagen und mit GPT verst\u00e4ndlich erkl\u00e4ren lassen. Das wollte ich ausprobieren. Das Ergebnis ist PerfMatters \u2013 ein Tool, das Web-Performance analysiert, den SpeedIndex vorhersagt und in verst\u00e4ndlicher Sprache erkl\u00e4rt, was eine Seite langsam macht. Der Stack: &hellip; <a href=\"https:\/\/stefan.boeck.name\/de\/2026\/01\/02\/perfmatters-von-der-idee-zum-launch\/\" class=\"more-link\"><span class=\"screen-reader-text\">PerfMatters: Von der Idee zum Launch<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-76","post","type-post","status-publish","format-standard","hentry","category-perfmatters"],"_links":{"self":[{"href":"https:\/\/stefan.boeck.name\/de\/wp-json\/wp\/v2\/posts\/76","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stefan.boeck.name\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stefan.boeck.name\/de\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/stefan.boeck.name\/de\/wp-json\/wp\/v2\/comments?post=76"}],"version-history":[{"count":2,"href":"https:\/\/stefan.boeck.name\/de\/wp-json\/wp\/v2\/posts\/76\/revisions"}],"predecessor-version":[{"id":80,"href":"https:\/\/stefan.boeck.name\/de\/wp-json\/wp\/v2\/posts\/76\/revisions\/80"}],"wp:attachment":[{"href":"https:\/\/stefan.boeck.name\/de\/wp-json\/wp\/v2\/media?parent=76"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stefan.boeck.name\/de\/wp-json\/wp\/v2\/categories?post=76"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stefan.boeck.name\/de\/wp-json\/wp\/v2\/tags?post=76"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}